{"id":11357,"date":"2017-12-05T17:07:54","date_gmt":"2017-12-05T16:07:54","guid":{"rendered":"https:\/\/kamerpower.com\/?p=11357"},"modified":"2024-01-26T22:55:26","modified_gmt":"2024-01-26T21:55:26","slug":"concours-police-2016-cote-divoire-enp-ci-2016-2017","status":"publish","type":"post","link":"https:\/\/kamerpower.com\/fr\/concours-police-2016-cote-divoire-enp-ci-2016-2017\/","title":{"rendered":"Concours police 2024 cote d&#8217;ivoire ENP ci 2024-2025"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Contents<\/p>\n<label for=\"ez-toc-cssicon-toggle-item-6a580f62d4cff\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"ez-toc-cssicon\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #000000;color:#000000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #000000;color:#000000\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a580f62d4cff\"  aria-label=\"Toggle\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/kamerpower.com\/fr\/concours-police-2016-cote-divoire-enp-ci-2016-2017\/#concours-police-2024-cote-divoire-enp-ci-2024-2025\" >Concours police 2024 cote d&#8217;ivoire ENP ci 2024-2025<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/kamerpower.com\/fr\/concours-police-2016-cote-divoire-enp-ci-2016-2017\/#presentation\" >Pr\u00e9sentation<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/kamerpower.com\/fr\/concours-police-2016-cote-divoire-enp-ci-2016-2017\/#les-metiers-de-la-police-nationale-ci-enp-cote-divoire-ci\" >Les Metiers de la Police Nationale ci (ENP cote d&#8217;ivoire ci)<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/kamerpower.com\/fr\/concours-police-2016-cote-divoire-enp-ci-2016-2017\/#concours-police-2024-cote-divoire-enp-ci-2024-2025-2\" >Concours police 2024 cote d&#8217;ivoire ENP ci 2024-2025.<\/a><\/li><\/ul><\/nav><\/div>\n<h3 style=\"text-align: center;\"><span class=\"ez-toc-section\" id=\"concours-police-2024-cote-divoire-enp-ci-2024-2025\"><\/span><span style=\"color: #3366ff;\"><strong>Concours police 2024 cote d&#8217;ivoire ENP ci 2024-2025<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<h3><span class=\"ez-toc-section\" id=\"presentation\"><\/span><span style=\"color: #ff0000;\"><strong>Pr\u00e9sentation<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">1967 \u2013 2008 : (Concours police 2024 <span style=\"color: #ff0000;\">cote d&#8217;ivoire<\/span> ENP ci 2024-2025) Quarante et une longues ann\u00e9es durant lesquelles, l\u2019<a href=\"https:\/\/kamerpower.com\/fr\/liste-concours-direct-2015-2016-mfpra-cote-divoire\/\"><strong>Ecole Nationale de Police<\/strong> (<strong>ENP ci<\/strong>)<\/a> existe sur son site actuel. Elle a ouvert ses portes d\u2019abord aux fils de la C\u00f4te d\u2019Ivoire, mais \u00e9galement \u00e0 ceux et celles de nombreux pays voisins et lointains : le <strong>Burkina Faso<\/strong>, le <strong>Togo<\/strong>, le <strong>B\u00e9nin<\/strong>, la <strong>R\u00e9publique Centrafricaine<\/strong>, etc. Puis, aux filles du pays, en 1988. Durant toutes ces ann\u00e9es, elle avait pour seule vocation, la formation initiale des Commissaires, Officiers, et Sous Officiers de Police.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Depuis 1992, l\u2019Ecole Nationale de Police (<strong>ENP ci cote d&#8217;ivoire<\/strong>) est devenue une direction centrale ayant une double vocation : la formation initiale et la formation continue de l\u2019ensemble des personnels de la <strong>Police Nationale ci<\/strong>. De cette double casquette, ressort son appellation actuelle de Direction de la Formation et de l\u2019Ecole Nationale de Police. Ses missions et son organisation d\u00e9coulent de sa double vocation.<\/span><\/p>\n<p style=\"text-align: justify;\">L<span style=\"color: #000000;\">e Minist\u00e8re d\u2019Etat, Minist\u00e8re de l\u2019Int\u00e9rieur et de la S\u00e9curit\u00e9 porte \u00e0 la connaissance des candidats aux concours directs de recrutement des \u00e9l\u00e8ves Commissaires, Officiers et Sous- Officiers de Police session 2023-2024.<\/span><\/p>\n<h3 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"les-metiers-de-la-police-nationale-ci-enp-cote-divoire-ci\"><\/span><span style=\"color: #ff0000;\"><strong>Les Metiers de la Police Nationale ci (ENP cote d&#8217;ivoire ci)<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-11319 size-full\" src=\"https:\/\/kamerpower.com\/wp-content\/uploads\/2015\/12\/education-nationale-ci.png\" alt=\"education nationale ci c\u00f4te d'ivoire\" width=\"1280\" height=\"720\" srcset=\"https:\/\/kamerpower.com\/wp-content\/uploads\/2015\/12\/education-nationale-ci.png 1280w, https:\/\/kamerpower.com\/wp-content\/uploads\/2015\/12\/education-nationale-ci-600x338.png 600w, https:\/\/kamerpower.com\/wp-content\/uploads\/2015\/12\/education-nationale-ci-300x169.png 300w, https:\/\/kamerpower.com\/wp-content\/uploads\/2015\/12\/education-nationale-ci-768x432.png 768w, https:\/\/kamerpower.com\/wp-content\/uploads\/2015\/12\/education-nationale-ci-1024x576.png 1024w, https:\/\/kamerpower.com\/wp-content\/uploads\/2015\/12\/education-nationale-ci-520x293.png 520w, https:\/\/kamerpower.com\/wp-content\/uploads\/2015\/12\/education-nationale-ci-1200x675.png 1200w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Etablissement public \u00e0 caract\u00e8re administratif (<strong>E.P.N ci<\/strong>), elle est rattach\u00e9e \u00e0 la Direction G\u00e9n\u00e9rale de la Police Nationale qui elle-m\u00eame est plac\u00e9e sous la tutelle du Minist\u00e8re de l\u2019Int\u00e9rieur.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">L\u2019Ecole Nationale de Police (<strong>E.N.P ci<\/strong>) est la seule \u00e9cole de formation de l\u2019ensemble des personnels de la Police Nationale de C\u00f4te d\u2019Ivoire, elle a pour mission principale d\u2019assurer :<\/span><\/p>\n<ul>\n<li><span style=\"color: #000000;\">la formation initiale et continue de tous les corps policiers (conception, direction, contr\u00f4le, et ex\u00e9cution)<\/span><\/li>\n<li><span style=\"color: #000000;\">la formation de formateurs dans les domaines et apprentissages des m\u00e9tiers sp\u00e9cifiques de la Police<\/span><\/li>\n<\/ul>\n<h2 style=\"text-align: center;\"><span class=\"ez-toc-section\" id=\"concours-police-2024-cote-divoire-enp-ci-2024-2025-2\"><\/span><span style=\"color: #3366ff;\"><strong>Concours police 2024 cote d&#8217;ivoire ENP ci 2024-2025.<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n","protected":false},"excerpt":{"rendered":"<p>&#46;&#46;&#46;<\/p>\n","protected":false},"author":716,"featured_media":11319,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[1942],"tags":[1987,1945,1944],"class_list":["post-11357","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cote-divoire","tag-concours-cote-divoire-2016-2017","tag-concours-de-recrutement-de-la-fonction-publique-mfpra","tag-mfpra-concours-cote-divoire"],"_links":{"self":[{"href":"https:\/\/kamerpower.com\/fr\/wp-json\/wp\/v2\/posts\/11357","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kamerpower.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kamerpower.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kamerpower.com\/fr\/wp-json\/wp\/v2\/users\/716"}],"replies":[{"embeddable":true,"href":"https:\/\/kamerpower.com\/fr\/wp-json\/wp\/v2\/comments?post=11357"}],"version-history":[{"count":1,"href":"https:\/\/kamerpower.com\/fr\/wp-json\/wp\/v2\/posts\/11357\/revisions"}],"predecessor-version":[{"id":76573,"href":"https:\/\/kamerpower.com\/fr\/wp-json\/wp\/v2\/posts\/11357\/revisions\/76573"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kamerpower.com\/fr\/wp-json\/wp\/v2\/media\/11319"}],"wp:attachment":[{"href":"https:\/\/kamerpower.com\/fr\/wp-json\/wp\/v2\/media?parent=11357"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kamerpower.com\/fr\/wp-json\/wp\/v2\/categories?post=11357"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kamerpower.com\/fr\/wp-json\/wp\/v2\/tags?post=11357"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}