{"id":15509,"date":"2016-09-05T12:45:30","date_gmt":"2016-09-05T11:45:30","guid":{"rendered":"https:\/\/kamerpower.com\/fr\/?p=15509"},"modified":"2016-09-05T12:49:21","modified_gmt":"2016-09-05T11:49:21","slug":"palais-presidentiel-du-cameroun-palais-de-lunite-et-photo","status":"publish","type":"post","link":"https:\/\/kamerpower.com\/fr\/palais-presidentiel-du-cameroun-palais-de-lunite-et-photo\/","title":{"rendered":"Palais presidentiel du Cameroun Palais de l&#8217;Unit\u00e9 (et photo)"},"content":{"rendered":"<h3 style=\"text-align: center;\"><span style=\"color: #3366ff;\"><strong>Palais presidentiel du Cameroun Palais de l&#8217;Unit\u00e9 (photo palais pr\u00e9sidentiel cameroun).<\/strong><\/span><\/h3>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Palais presidentiel du Cameroun Palais de l&#8217;Unit\u00e9, photo <a href=\"https:\/\/kamerpower.com\/fr\/presidence-de-la-republique-du-cameroun\/\"><strong>palais pr\u00e9sidentiel cameroun.<\/strong><\/a> Faisons un peu d&#8217;histoire. Jusqu&#8217;en <strong>1918<\/strong>, le Cameroun \u00e9tait sous protectorat allemand. A la fin de . L&#8217;ancien Palais Pr\u00e9sidentiel. Le Palais de l&#8217;Unit\u00e9 Cameroun.<\/span><\/p>\n<p style=\"text-align: justify;\"><img decoding=\"async\" class=\"aligncenter wp-image-15506 size-full\" src=\"https:\/\/kamerpower.com\/wp-content\/uploads\/2016\/09\/Pr\u00e9sidence-de-la-r\u00e9publique-du-cameroun-prc-photo-du-palais-presidentiel-du-cameroun.jpg\" alt=\"Pr\u00e9sidence de la r\u00e9publique du cameroun prc photo du palais presidentiel du cameroun\" width=\"363\" height=\"240\" \/><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Le <strong>Palais de l&#8217;Unit\u00e9<\/strong> est le nom de la r\u00e9sidence du Chef de l\u2019\u00c9tat du Cameroun. Situ\u00e9 \u00e0 <strong>Yaound\u00e9<\/strong>, il abrite \u00e9galement la plupart des services li\u00e9s \u00e0 la Pr\u00e9sidence de la R\u00e9publique et du secr\u00e9tariat g\u00e9n\u00e9ral de la R\u00e9publique\u00a0et l&#8217;actuel r\u00e9sident du palais de l&#8217;Unit\u00e9 est <strong>Paul Biya<\/strong>, pr\u00e9sident du Cameroun depuis le 6 novembre 1982.<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #008000;\"><strong>Les photo du palais presidentiel du cameroun.<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Vaste complexe immobilier, le palais d\u2019<strong>Etoudi Yaounde<\/strong>, \u00ab palais de l\u2019unit\u00e9 \u00bb, dessin\u00e9 par Olivier-Cl\u00e9ment Cacoub, un architecte franco-tunisien (<strong>14 avril 1920 &#8211; 25 avril 2008<\/strong>), abrite les bureaux de fonction et la r\u00e9sidence du pr\u00e9sident de la r\u00e9publique du Cameroun.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Le b\u00e2timent principal (<strong>le palais<\/strong>) tr\u00f4ne au milieu de ce complexe qui s\u2019\u00e9tale sur plusieurs hectares au-dessus d\u2019une colline appartenant initialement aux Etoudi, l\u2019un des nombreux groupes autochtones de la capitale camerounaise.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Comme l\u2019ensemble des ouvrages que Cacoub a sign\u00e9s, palais de Mobutu dans son village natal \u00e0 Gbadolite, Basilique de Yamoussoukro dans celui d\u2019Houphou\u00ebt, le palais de l\u2019unit\u00e9 est une \u0153uvre issue de \u00ab l\u2019alliage de l\u2019art baroque et oriental de certaines de ses \u0153uvres au luxe insolent \u00bb.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">La construction du palais de l\u2019unit\u00e9 remonte au d\u00e9but des ann\u00e9es 1980. Inaugur\u00e9 par feu le pr\u00e9sident Ahidjo moins de quatre mois avant sa d\u00e9mission en novembre 1982, le palais d\u2019Etoudi est une forteresse.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Le b\u00e2timent, un v\u00e9ritable site touristique pour son immensit\u00e9 et sa beaut\u00e9 architecturale, est interdit au grand public. Le pr\u00e9sident n\u2019y re\u00e7oit que des officiels tri\u00e9s sur le volet, et quelques privil\u00e9gi\u00e9s lors d\u2019une soir\u00e9e de gala organis\u00e9e au soir du 20 mai, jour de la f\u00eate nationale.<\/span><\/p>\n<h2 style=\"text-align: center;\"><span style=\"color: #3366ff;\"><strong>Palais presidentiel du Cameroun Palais de l&#8217;Unit\u00e9 (photo palais pr\u00e9sidentiel cameroun).<\/strong><\/span><\/h2>\n","protected":false},"excerpt":{"rendered":"<p>&#46;&#46;&#46;<\/p>\n","protected":false},"author":1,"featured_media":15506,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[103],"tags":[],"class_list":["post-15509","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cameroun"],"_links":{"self":[{"href":"https:\/\/kamerpower.com\/fr\/wp-json\/wp\/v2\/posts\/15509","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kamerpower.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kamerpower.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kamerpower.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/kamerpower.com\/fr\/wp-json\/wp\/v2\/comments?post=15509"}],"version-history":[{"count":0,"href":"https:\/\/kamerpower.com\/fr\/wp-json\/wp\/v2\/posts\/15509\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kamerpower.com\/fr\/wp-json\/wp\/v2\/media\/15506"}],"wp:attachment":[{"href":"https:\/\/kamerpower.com\/fr\/wp-json\/wp\/v2\/media?parent=15509"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kamerpower.com\/fr\/wp-json\/wp\/v2\/categories?post=15509"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kamerpower.com\/fr\/wp-json\/wp\/v2\/tags?post=15509"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}