{"id":18508,"date":"2017-04-21T00:13:06","date_gmt":"2017-04-20T23:13:06","guid":{"rendered":"https:\/\/kamerpower.com\/?p=18508\/"},"modified":"2024-03-27T02:15:35","modified_gmt":"2024-03-27T01:15:35","slug":"cuso-international-cameroun-recrutement-assistante-la-logistique-et-lapprovisionnement","status":"publish","type":"post","link":"https:\/\/kamerpower.com\/fr\/cuso-international-cameroun-recrutement-assistante-la-logistique-et-lapprovisionnement\/","title":{"rendered":"CUSO International cameroun recrutement: Assistant(e) \u00e0 la Logistique et \u00e0 l\u2019Approvisionnement"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_83 counter-hierarchy ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Contents<\/p>\n<label for=\"ez-toc-cssicon-toggle-item-6a03f2dfb0175\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"ez-toc-cssicon\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #000000;color:#000000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #000000;color:#000000\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a03f2dfb0175\"  aria-label=\"Toggle\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/kamerpower.com\/fr\/cuso-international-cameroun-recrutement-assistante-la-logistique-et-lapprovisionnement\/#cuso-international-cameroun-recrutement-assistante-a-la-logistique-et-a-lapprovisionnement\" >CUSO International cameroun recrutement: Assistant(e) \u00e0 la Logistique et \u00e0 l\u2019Approvisionnement.<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/kamerpower.com\/fr\/cuso-international-cameroun-recrutement-assistante-la-logistique-et-lapprovisionnement\/#qualifications\" >Qualifications :<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/kamerpower.com\/fr\/cuso-international-cameroun-recrutement-assistante-la-logistique-et-lapprovisionnement\/#comment-postuler\" >Comment postuler ?<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/kamerpower.com\/fr\/cuso-international-cameroun-recrutement-assistante-la-logistique-et-lapprovisionnement\/#cuso-international-cameroun-recrutement-assistante-a-la-logistique-et-a-lapprovisionnement-2\" >CUSO International cameroun recrutement: Assistant(e) \u00e0 la Logistique et \u00e0 l\u2019Approvisionnement.<\/a><\/li><\/ul><\/nav><\/div>\n<h3 style=\"text-align: center;\"><span class=\"ez-toc-section\" id=\"cuso-international-cameroun-recrutement-assistante-a-la-logistique-et-a-lapprovisionnement\"><\/span><span style=\"color: #3366ff;\"><strong>CUSO International cameroun recrutement: Assistant(e) \u00e0 la Logistique et \u00e0 l\u2019Approvisionnement.<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p style=\"text-align: justify;\">Le CUSO International lance le recrutement d\u2019un(e) Assistant (e) \u00e0 la Logistique et \u00e0 l\u2019Approvisionnement.\u00a0<a href=\"https:\/\/kamerpower.com\/fr\/cuso-international-recrutement-montreal-canada-cameroun-ottawa\/\"><strong>CUSO<\/strong><\/a> International cameroun recrutement: Assistant(e) \u00e0 la Logistique et \u00e0 l\u2019Approvisionnement.<\/p>\n<p><span style=\"color: #000000;\">Vous \u00eates \u00e0 la recherche d\u2019une carri\u00e8re enrichissante qui vous permettrait d\u2019apporter des solutions durables aux probl\u00e8mes de pauvret\u00e9, d\u2019exclusion et d\u2019in\u00e9galit\u00e9? Cuso International a ce qu\u2019il vous faut!<\/span><\/p>\n<p style=\"text-align: justify;\"><img decoding=\"async\" class=\"aligncenter wp-image-18509 size-full\" src=\"https:\/\/kamerpower.com\/wp-content\/uploads\/2017\/04\/CUSO-International-cameroun-recrutement-Assistante-\u00e0-la-Logistique-et-\u00e0-l\u2019Approvisionnement.jpg\" alt=\"CUSO International cameroun recrutement Assistant(e) \u00e0 la Logistique et \u00e0 l\u2019Approvisionnement\" width=\"160\" height=\"160\" srcset=\"https:\/\/kamerpower.com\/wp-content\/uploads\/2017\/04\/CUSO-International-cameroun-recrutement-Assistante-\u00e0-la-Logistique-et-\u00e0-l\u2019Approvisionnement-300x300.jpg 300w, https:\/\/kamerpower.com\/wp-content\/uploads\/2017\/04\/CUSO-International-cameroun-recrutement-Assistante-\u00e0-la-Logistique-et-\u00e0-l\u2019Approvisionnement-100x100.jpg 100w, https:\/\/kamerpower.com\/wp-content\/uploads\/2017\/04\/CUSO-International-cameroun-recrutement-Assistante-\u00e0-la-Logistique-et-\u00e0-l\u2019Approvisionnement-150x150.jpg 150w, https:\/\/kamerpower.com\/wp-content\/uploads\/2017\/04\/CUSO-International-cameroun-recrutement-Assistante-\u00e0-la-Logistique-et-\u00e0-l\u2019Approvisionnement-96x96.jpg 96w\" sizes=\"(max-width: 160px) 100vw, 160px\" \/><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Cuso International est un ardent d\u00e9fenseur de la diversit\u00e9. En tant qu\u2019employeur souscrivant au principe de l\u2019\u00e9galit\u00e9 d\u2019acc\u00e8s \u00e0 l\u2019emploi, Cuso International recrute ses employ\u00e9s sans \u00e9gard \u00e0 leur origine ethnique, \u00e0 leur religion, \u00e0 leur genre, \u00e0 leur \u00e2ge, \u00e0 leur sexualit\u00e9 ou \u00e0 leur handicap.<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>Lieu d\u2019affectation<\/strong> : Yaound\u00e9, Cameroun.<\/span><\/p>\n<h3><span class=\"ez-toc-section\" id=\"qualifications\"><\/span><span style=\"color: #3366ff;\"><strong>Qualifications :<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li style=\"text-align: justify;\">Dipl\u00f4me en administration et\/ou une combinaison d\u2019\u00e9tudes, de formation et d\u2019exp\u00e9rience de travail reli\u00e9e aux exigences du poste.<\/li>\n<li style=\"text-align: justify;\">Minimum de deux ans d\u2019exp\u00e9rience professionnelle en administration notamment dans le domaine de l\u2019immobilier, la gestion de mat\u00e9riel et d\u2019\u00e9quipement et l\u2019appui aux ressources humaines.<\/li>\n<li style=\"text-align: justify;\">Connaissances de la r\u00e9glementation nationale li\u00e9e \u00e0 l\u2019immobilier, le transport, visas et permis de s\u00e9jour.<\/li>\n<li style=\"text-align: justify;\">Etre bilingue.<\/li>\n<\/ul>\n<h3><span class=\"ez-toc-section\" id=\"comment-postuler\"><\/span><span style=\"color: #3366ff;\"><strong>Comment postuler ?<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li>CV de deux pages au plus ;<\/li>\n<li>Une lettre de motivation.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Les documents doivent \u00eatre en Word ou en PDF, les candidatures doivent \u00eatre soumises \u00e0 l\u2019adresse email : hr.westafrica@cusointernationa.org , en indiquant clairement l\u2019objet.<\/p>\n<p><strong>NB<\/strong> : pour la description compl\u00e8te du poste voir : www.cusointernational.org\/<\/p>\n<p>D\u00e9lai de d\u00e9p\u00f4t : le 24 avril 2023 \u00e0 17 heures.<\/p>\n<h2 style=\"text-align: center;\"><span class=\"ez-toc-section\" id=\"cuso-international-cameroun-recrutement-assistante-a-la-logistique-et-a-lapprovisionnement-2\"><\/span><span style=\"color: #3366ff;\"><strong>CUSO International cameroun recrutement: Assistant(e) \u00e0 la Logistique et \u00e0 l\u2019Approvisionnement.<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n","protected":false},"excerpt":{"rendered":"<p>&#46;&#46;&#46;<\/p>\n","protected":false},"author":1,"featured_media":18509,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[1845],"tags":[2248,1968,1973],"class_list":["post-18508","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-emplois","tag-cuso-international-emploi","tag-les-offre-demploi-au-cameroun","tag-offre-demploi-au-cameroun-2016-2017"],"_links":{"self":[{"href":"https:\/\/kamerpower.com\/fr\/wp-json\/wp\/v2\/posts\/18508","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kamerpower.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kamerpower.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kamerpower.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/kamerpower.com\/fr\/wp-json\/wp\/v2\/comments?post=18508"}],"version-history":[{"count":0,"href":"https:\/\/kamerpower.com\/fr\/wp-json\/wp\/v2\/posts\/18508\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kamerpower.com\/fr\/wp-json\/wp\/v2\/media\/18509"}],"wp:attachment":[{"href":"https:\/\/kamerpower.com\/fr\/wp-json\/wp\/v2\/media?parent=18508"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kamerpower.com\/fr\/wp-json\/wp\/v2\/categories?post=18508"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kamerpower.com\/fr\/wp-json\/wp\/v2\/tags?post=18508"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}