{"id":38313,"date":"2024-06-23T08:16:00","date_gmt":"2024-06-23T07:16:00","guid":{"rendered":"https:\/\/kamerpower.com\/?p=38313"},"modified":"2026-03-17T13:08:50","modified_gmt":"2026-03-17T12:08:50","slug":"concours-iut-douala-2021-2022-cycle-bts-premiere-annee","status":"publish","type":"post","link":"https:\/\/kamerpower.com\/fr\/concours-iut-douala-2021-2022-cycle-bts-premiere-annee\/","title":{"rendered":"Concours IUT douala 2026-2027 cycle BTS Premi\u00e8re Ann\u00e9e"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Contents<\/p>\n<label for=\"ez-toc-cssicon-toggle-item-6a97ea18f1f20\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"ez-toc-cssicon\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #000000;color:#000000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #000000;color:#000000\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a97ea18f1f20\"  aria-label=\"Toggle\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/kamerpower.com\/fr\/concours-iut-douala-2021-2022-cycle-bts-premiere-annee\/#concours-iut-douala-2026-2027-cycle-bts-premiere-annee\" >Concours IUT douala 2026-2027 cycle BTS Premi\u00e8re Ann\u00e9e<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/kamerpower.com\/fr\/concours-iut-douala-2021-2022-cycle-bts-premiere-annee\/#quelles-sont-les-filieres-de-liut-de-douala\" >Quelles sont les fili\u00e8res de l&#8217;IUT de Douala ?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/kamerpower.com\/fr\/concours-iut-douala-2021-2022-cycle-bts-premiere-annee\/#article-4-linscription-se-fait-en-ligne-au-site-wwwiut-doualacm\" >Article 4: L\u2019inscription se fait en ligne au site www.iut-douala.cm<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/kamerpower.com\/fr\/concours-iut-douala-2021-2022-cycle-bts-premiere-annee\/#article-5\" >Article 5\u00a0:<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/kamerpower.com\/fr\/concours-iut-douala-2021-2022-cycle-bts-premiere-annee\/#faqs-concours-iut-douala-2026-2027-cycle-bts-premiere-annee\" >FAQs: Concours IUT douala 2026-2027 cycle BTS Premi\u00e8re Ann\u00e9e<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h2 style=\"text-align: center;\"><span class=\"ez-toc-section\" id=\"concours-iut-douala-2026-2027-cycle-bts-premiere-annee\"><\/span><span style=\"color: #000000;\"><strong>Concours IUT douala 2026-2027 cycle BTS Premi\u00e8re Ann\u00e9e<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<hr \/>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\"><strong><a href=\"https:\/\/kamerpower.com\/fr\/concours-iut-de-douala-cameroun-2015-2016-universite-de-douala-premiere-annee\/\">Concours IUT douala cycle BTS Premi\u00e8re Ann\u00e9e<\/a><span style=\"color: #ff0000;\"><br \/><\/span><\/strong><\/span><\/p>\n<p style=\"text-align: justify;\">Ponant recrutement en <span style=\"color: #3366ff;\"><strong>Premi\u00e8re Ann\u00e9e<\/strong><\/span> du <span style=\"color: #3366ff;\"><strong>cycle de Brevet de Technicien Sup\u00e9rieur (BTS)<\/strong> <\/span>de l&#8217;institut Universitaire de Technologie (IUT) de l&#8217;Universit\u00e9 de Douala, et fixant le nombre de places offertes, au titre de l&#8217;ann\u00e9e acad\u00e9mique 2026-2027.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-38314 size-full\" src=\"https:\/\/kamerpower.com\/wp-content\/uploads\/2021\/06\/Concours-IUT-douala-2021-2022-filiere-universite-de-douala.png\" alt=\"Concours IUT douala 2026-2027 fili\u00e8re universit\u00e9 de douala\" width=\"1890\" height=\"945\" srcset=\"https:\/\/kamerpower.com\/wp-content\/uploads\/2021\/06\/Concours-IUT-douala-2021-2022-filiere-universite-de-douala.png 1890w, https:\/\/kamerpower.com\/wp-content\/uploads\/2021\/06\/Concours-IUT-douala-2021-2022-filiere-universite-de-douala-600x300.png 600w, https:\/\/kamerpower.com\/wp-content\/uploads\/2021\/06\/Concours-IUT-douala-2021-2022-filiere-universite-de-douala-300x150.png 300w, https:\/\/kamerpower.com\/wp-content\/uploads\/2021\/06\/Concours-IUT-douala-2021-2022-filiere-universite-de-douala-768x384.png 768w, https:\/\/kamerpower.com\/wp-content\/uploads\/2021\/06\/Concours-IUT-douala-2021-2022-filiere-universite-de-douala-1536x768.png 1536w, https:\/\/kamerpower.com\/wp-content\/uploads\/2021\/06\/Concours-IUT-douala-2021-2022-filiere-universite-de-douala-720x360.png 720w, https:\/\/kamerpower.com\/wp-content\/uploads\/2021\/06\/Concours-IUT-douala-2021-2022-filiere-universite-de-douala-520x260.png 520w, https:\/\/kamerpower.com\/wp-content\/uploads\/2021\/06\/Concours-IUT-douala-2021-2022-filiere-universite-de-douala-320x160.png 320w, https:\/\/kamerpower.com\/wp-content\/uploads\/2021\/06\/Concours-IUT-douala-2021-2022-filiere-universite-de-douala-150x75.png 150w, https:\/\/kamerpower.com\/wp-content\/uploads\/2021\/06\/Concours-IUT-douala-2021-2022-filiere-universite-de-douala-1200x600.png 1200w\" sizes=\"(max-width: 1890px) 100vw, 1890px\" \/><\/p>\n<p><span style=\"color: #000000;\"><span style=\"color: #3366ff;\"><strong>Article 1er :<\/strong> <\/span>Un recrutement en premi\u00e8re ann\u00e9e du cycle de Brevet de Technicien Sup\u00e9rieur (BTS) est <\/span><span style=\"color: #000000;\">ouvert \u00e0 l\u2019Institut Universitaire de Technologie de l&#8217;Universit\u00e9 de Douala (IUT) pour le compte de <\/span><span style=\"color: #000000;\">ann\u00e9e acad\u00e9mique 2026\/2027, dans les sp\u00e9cialit\u00e9s sn\u00e9cifiges 4 l&#8217;article 3 ci-dessous.<\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"color: #3366ff;\"><strong>Article 2.<\/strong><\/span> Le recrutement vise a l&#8217;article 1er ci-dessus est ouvert aux camerounais d\u00e9s Jeux (UT) sexes et <\/span><span style=\"color: #000000;\">aux candidats \u00e9trangers et se fait sur \u00e9tude d\u00e9 dossier.<\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"color: #3366ff;\"><strong>Article 3 :<\/strong><\/span> Le nombre total de places offertes est \u00e9gal \u00e0 cinq cents (500) places r\u00e9parties.<\/span><\/p>\n<h3><span class=\"ez-toc-section\" id=\"quelles-sont-les-filieres-de-liut-de-douala\"><\/span><strong>Quelles sont les fili\u00e8res de l&#8217;IUT de Douala ?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li><strong>Institut Universitaire de Technologie (IUT) de Douala.<\/strong><\/li>\n<li><strong>G\u00e9nie Electrique et Informatique Industriel(GEII).<\/strong><\/li>\n<li><strong>G\u00e9nie Industriel et Maintenance (GIM)<\/strong><\/li>\n<li><strong>G\u00e9nie M\u00e9canique et Productique(GMP).<\/strong><\/li>\n<li><strong>G\u00e9nie Thermique et Energie\u00a0<\/strong><\/li>\n<li><strong>Gestion des Entreprises et des Administrations<\/strong><\/li>\n<li><strong>G\u00e9nie logistique et transport.<\/strong><\/li>\n<li><strong>G\u00e9nie Informatique.<\/strong><\/li>\n<\/ul>\n<h3><span class=\"ez-toc-section\" id=\"article-4-linscription-se-fait-en-ligne-au-site-wwwiut-doualacm\"><\/span><span style=\"color: #000000;\"><span style=\"color: #3366ff;\"><strong>Article 4:<\/strong><\/span> L\u2019inscription se fait en ligne au site <strong>www.iut-douala.cm<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><span style=\"color: #000000;\">Le dossier physique \u00e0 d\u00e9poser au Service de la Scolarit\u00e9 de l&#8217;TUT de Douala jusqu&#8217;au <strong>06 Septembre 2025<\/strong>. d\u00e9lai de rigueur devra comporter les pi\u00e8ces suivantes:<\/span><\/p>\n<ol>\n<li><span style=\"color: #000000;\">Une fiche de renseignements d\u00fbment <span style=\"font-weight: bold;\">remplie\u00a0en ligne<\/span> (sur le site Web de l&#8217;IUT de Douala \u00e0 l&#8217;adresse:\u00a0<span style=\"font-weight: bold;\">www.iut-douala.cm<\/span>) \u00a0et timbr\u00e9e \u00e0 <span style=\"font-weight: bold; color: #ff0000;\">1000 FCFA<\/span>, mise \u00e0 la disposition des candidats\u00a0au Service de la Scolarit\u00e9 de l&#8217;IUT de Douala et dans toutes les d\u00e9l\u00e9gations r\u00e9gionales du minist\u00e8re des\u00a0Enseignements Secondaires des diff\u00e9rents Centres.\u00a0<\/span><\/li>\n<li><span style=\"color: #000000;\">Une photocopie certifi\u00e9e d&#8217;acte de naissance datant de moins de trois (3) mois.<\/span><\/li>\n<li><span style=\"color: #000000;\">Une copie certifi\u00e9e conforme de l&#8217;un des dipl\u00f4mes ouvrant droit au concours.\u00a0<\/span><\/li>\n<li><span style=\"color: #000000;\">Un certificat de scolarit\u00e9 de la classe de terminale<\/span><\/li>\n<li><span style=\"color: #000000;\">Un certificat m\u00e9dical d\u00e9livr\u00e9 par un m\u00e9decin fonctionnaire, datant de moins de trois\u00a0(03) mois et certifiant que le candidat est apte \u00e0 poursuivre des \u00e9tudes sup\u00e9rieures.\u00a0<\/span><\/li>\n<li><span style=\"color: #000000;\">\u00a0Quatre (04) photos d&#8217;identit\u00e9 4X4 du candidat.<\/span><\/li>\n<li><span style=\"color: #000000;\">Un re\u00e7u de versement bancaire d&#8217;un montant de vingt mille\u00a0<span style=\"color: #ff0000; font-weight: bold;\">(20 000) francs CFA<\/span>, \u00e0 titre des droits\u00a0d&#8217;inscription au concours \u00e0 verser au compte <span style=\"color: #3366ff; font-weight: bold;\">No.\u00a0<\/span><span style=\"color: #3366ff; font-weight: bold;\">10033 05214 14004000006<\/span> <span style=\"color: #ff0000; font-weight: bold;\">CLE 90<\/span><span style=\"font-weight: bold;\"> UBA<\/span>\u00a0.<\/span><\/li>\n<li><span style=\"color: #000000;\">Une enveloppe A4 (210X297) timbr\u00e9e \u00e0 400 francs CFA, portant l&#8217;adresse du candidat.\u00a0<\/span><\/li>\n<li style=\"text-align: justify;\"><span style=\"color: #000000;\">Ce concours est ouvert aux Camerounais des deux sexes et aux candidats \u00e9trangers \u00e2g\u00e9s de vingt &#8211; neuf (29) ans au plus au 1er janvier 2026.<\/span><\/li>\n<\/ol>\n<h3 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"article-5\"><\/span><span style=\"color: #3366ff; font-weight: bold;\">Article 5\u00a0:<\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Suite \u00e0 la publication des r\u00e9sultats, les candidats d\u00e9finitivement admis disposeront d&#8217;un d\u00e9lai de 15\u00a0jours \u00e0 compter de la date de d\u00e9but effectif des enseignements pour se pr\u00e9senter \u00e0 l&#8217;\u00e9tablissement, en vue de\u00a0remplir les formalit\u00e9s d&#8217;inscription. Pass\u00e9 ce d\u00e9lai, ceux qui ne se seront pas pr\u00e9sent\u00e9s \u00e0 l&#8217;\u00e9tablissement seront\u00a0consid\u00e9r\u00e9s comme d\u00e9missionnaires et, le cas \u00e9ch\u00e9ant, remplac\u00e9s par les candidats de la liste d&#8217;attente selon\u00a0l&#8217;ordre de m\u00e9rite, par d\u00e9cision du Ministre de l&#8217;Enseignement Sup\u00e9rieur, sur proposition du Recteur de\u00a0l&#8217;Universit\u00e9 de Douala.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #3366ff; font-weight: bold;\">Article 6\u00a0:<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Le Recteur de l&#8217;Universit\u00e9 de Douala, le Directeur des Accr\u00e9ditations Universitaires et de la Qualit\u00e9 et\u00a0le Directeur de l&#8217;IUT de Douala sont charg\u00e9s, chacun en ce qui le concerne, de l&#8217;ex\u00e9cution de la pr\u00e9sente d\u00e9cision\u00a0qui sera enregistr\u00e9e et communiqu\u00e9e en fran\u00e7ais et anglais partout o\u00f9 besoin sera.<\/span><\/p>\n<h3 style=\"text-align: center;\"><span class=\"ez-toc-section\" id=\"faqs-concours-iut-douala-2026-2027-cycle-bts-premiere-annee\"><\/span><span style=\"color: #000000;\"><strong>FAQs: Concours IUT douala 2026-2027 cycle BTS Premi\u00e8re Ann\u00e9e<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><span style=\"color: #000000;\"><strong>Recommandation\u00a0<\/strong><\/span><\/p>\n<ul>\n<li><a href=\"https:\/\/kamerpower.com\/fr\/concours-iut-de-douala-3eme-annee-2017-2018-universite-de-douala\/\"><strong>Concours IUT de Douala 3\u00e8me ann\u00e9e: Universit\u00e9 de Douala<\/strong><\/a><\/li>\n<li><a href=\"https:\/\/kamerpower.com\/fr\/iut-douala-institut-universitaire-de-technologie-de-douala-filieres\/\"><strong>IUT Douala Institut Universitaire de Technologie de douala Fili\u00e8res<\/strong><\/a><\/li>\n<li><a href=\"https:\/\/kamerpower.com\/fr\/brevet-de-technicien-superieur-bts-concour-2015-ouverture-de-lexamen-national-du-brevet-de-technicien-superieur-bts-session-de-juin-juillet-2015\/\"><strong>BTS Cameroun: Ouverture de l&#8217;examen national du Brevet de Technicien Superieur (BTS Cameroun)<\/strong><\/a><\/li>\n<\/ul>\n\n\n<div class=\"schema-faq wp-block-yoast-faq-block\"><div class=\"schema-faq-section\" id=\"faq-question-1773749167866\"><strong class=\"schema-faq-question\"><strong>Comment entrer \u00e0 l&#8217;IUT de Douala ?<\/strong><\/strong> <p class=\"schema-faq-answer\">L&#8217;admission \u00e0 l&#8217;IUT se fait par voie de concours sur \u00e9preuves \u00e9crites ou sur \u00e9tude de dossier.<\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1773749168732\"><strong class=\"schema-faq-question\"><strong>Quelles sont les fili\u00e8res de l&#8217;IUT de Douala ?<\/strong><\/strong> <p class=\"schema-faq-answer\">Quelles sont les fili\u00e8res de l&#8217;IUT de Douala ? Institut Universitaire de Technologie (IUT) de Douala, G\u00e9nie Electrique et Informatique Industriel(GEII), G\u00e9nie Industriel et Maintenance (GIM), G\u00e9nie M\u00e9canique et Productique(GMP), G\u00e9nie Thermique et Energie, Gestion des Entreprises et des Administrations, G\u00e9nie logistique et transport, G\u00e9nie Informatique.<\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1773749171778\"><strong class=\"schema-faq-question\"><strong>Comment s&#8217;inscrire \u00e0 l&#8217;IUT de Douala ?<\/strong><\/strong> <p class=\"schema-faq-answer\">Une fiche de renseignements d\u00fbment remplie\u00a0en ligne (sur le site Web de l&#8217;IUT de Douala \u00e0 l&#8217;adresse:\u00a0www.iut-douala.cm)\u00a0et timbr\u00e9e \u00e0 1000 FCFA, mise \u00e0 la disposition des candidats\u00a0au Service de la Scolarit\u00e9 de l&#8217;IUT de Douala et dans toutes les d\u00e9l\u00e9gations r\u00e9gionales du minist\u00e8re des\u00a0Enseignements Secondaires des diff\u00e9rents Centres.<\/p> <\/div> <\/div>\n","protected":false},"excerpt":{"rendered":"<p>&#46;&#46;&#46;<\/p>\n","protected":false},"author":686,"featured_media":38314,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[66],"tags":[1856,1826,1905],"class_list":["post-38313","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-concours","tag-epreuves-de-concours-de-liut-de-douala","tag-iut-universite-de-douala","tag-universite-de-douala"],"_links":{"self":[{"href":"https:\/\/kamerpower.com\/fr\/wp-json\/wp\/v2\/posts\/38313","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kamerpower.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kamerpower.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kamerpower.com\/fr\/wp-json\/wp\/v2\/users\/686"}],"replies":[{"embeddable":true,"href":"https:\/\/kamerpower.com\/fr\/wp-json\/wp\/v2\/comments?post=38313"}],"version-history":[{"count":2,"href":"https:\/\/kamerpower.com\/fr\/wp-json\/wp\/v2\/posts\/38313\/revisions"}],"predecessor-version":[{"id":77492,"href":"https:\/\/kamerpower.com\/fr\/wp-json\/wp\/v2\/posts\/38313\/revisions\/77492"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kamerpower.com\/fr\/wp-json\/wp\/v2\/media\/38314"}],"wp:attachment":[{"href":"https:\/\/kamerpower.com\/fr\/wp-json\/wp\/v2\/media?parent=38313"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kamerpower.com\/fr\/wp-json\/wp\/v2\/categories?post=38313"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kamerpower.com\/fr\/wp-json\/wp\/v2\/tags?post=38313"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}